{"id":781,"date":"2018-05-03T22:40:59","date_gmt":"2018-05-03T22:40:59","guid":{"rendered":"http:\/\/asipi.org\/brasil2018\/?page_id=781"},"modified":"2019-02-21T14:15:04","modified_gmt":"2019-02-21T14:15:04","slug":"sobre-brasil","status":"publish","type":"page","link":"https:\/\/asipi.org\/brasil2018\/sobre-brasil\/","title":{"rendered":"Sobre Brasil"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"porto-u-heading  wpb_custom_95aa9a11c17ad45cfabaf210d84ee7cc porto-u-8475\"><div class=\"porto-u-main-heading\"><h2  >Sobre Brasil<\/h2><\/div><style>.porto-u-8475.porto-u-heading{text-align:center}<\/style><\/div>[vc_separator color=\u00bbgreen\u00bb align=\u00bbalign_left\u00bb border_width=\u00bb4&#8243; el_width=\u00bb70&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb2\/3&#8243;][vc_tta_tour color=\u00bbgreen\u00bb active_section=\u00bb1&#8243; no_fill_content_area=\u00bbtrue\u00bb][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-user\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbSalud\u00bb tab_id=\u00bb1525446452216-012660fe-7ecd\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">No hay requisitos de salud obligatorios para ingresar a Brasil. Se recomiendan precauciones para la fiebre amarilla, la fiebre tifoidea, la polio y la malaria. Sugerimos que contacte a su G.P. para obtener consejos y recomendaciones actuales o llamar por tel\u00e9fono a una de las organizaciones que se detallan a continuaci\u00f3n. Se le aconseja tener cobertura de seguro m\u00e9dico completo. Tenga en cuenta que si ingresa a Brasil a trav\u00e9s de Per\u00fa, Ecuador o Colombia, se le solicitar\u00e1 que presente un certificado de vacunaci\u00f3n contra la fiebre amarilla actualizado para fines de inmigraci\u00f3n. Evite comer y beber productos locales de vendedores ambulantes y restaurantes con pr\u00e1cticas sospechosas de higiene o refrigeraci\u00f3n. Es aconsejable beber solo agua embotellada en todo momento.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-user\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbVisa y Vacunas\u00bb tab_id=\u00bb1525885126324-ab095f97-b4e6&#8243;][vc_column_text]<\/p>\n<h3 style=\"text-align: justify;\">Visa<\/h3>\n<p style=\"text-align: justify;\">Dise\u00f1ados para ayudar a los participantes a cumplir con los requisitos administrativos en ciertos pa\u00edses, se pueden suministrar cartas oficiales de invitaci\u00f3n para la entrada o para otros fines a pedido. Por favor espere el tiempo suficiente para este procedimiento. Tenga en cuenta que tales cartas no comprometen al Comit\u00e9 Organizador a ning\u00fan tipo de apoyo financiero, arreglo de alojamiento, ni garantiza un problema de visa de entrada. Tenga en cuenta que las cartas de invitaci\u00f3n ser\u00e1n emitidas por el Comit\u00e9 Organizador despu\u00e9s de que el participante se haya registrado. Por lo tanto, debe completar el formulario de registro lo antes posible para poder obtener su visa a tiempo para el Simposio. Se recomienda encarecidamente a los participantes que se aseguren de cumplir con todos los requisitos legales para ingresar a Brasil. Adem\u00e1s de un pasaporte v\u00e1lido, tambi\u00e9n se puede requerir una visa de entrada. Las visas son requeridas solo para visitantes que vienen de pa\u00edses que requieren visas para ciudadanos brasile\u00f1os. Para obtener su visa brasile\u00f1a, vea las instrucciones m\u00e1s adelante.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan el Ministerio de Relaciones Exteriores, los ciudadanos de los siguientes pa\u00edses no necesitan visas:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-801 aligncenter\" src=\"https:\/\/asipi.org\/brasil2018\/wp-content\/uploads\/sites\/13\/2018\/05\/vaccines_01.jpg\" alt=\"\" width=\"403\" height=\"576\" \/><\/p>\n<p style=\"text-align: justify;\">Lo siguiente es muy importante para informarle que el gobierno brasile\u00f1o puede cambiar estas condiciones diplom\u00e1ticas sin previo aviso.<\/p>\n<p style=\"text-align: center;\">POR FAVOR, COMPRUEBE CON SU CONSULADO BRASILE\u00d1O M\u00c1S CERCANO<\/p>\n<h3 style=\"text-align: justify;\">eVisas<\/h3>\n<p style=\"text-align: justify;\">La Visa Electr\u00f3nica de la Rep\u00fablica Federativa de Brasil es una nueva aplicaci\u00f3n de Visa hecha por Internet, que los ciudadanos australianos, japoneses, canadienses y estadounidenses pueden solicitar para entrar en territorio brasile\u00f1o.<\/p>\n<h3>Vacunas<\/h3>\n<p style=\"text-align: justify;\">El gobierno brasile\u00f1o exige un certificado internacional de vacunaci\u00f3n contra la fiebre amarilla para los viajeros que han estado en los \u00faltimos tres meses o que provienen de estos pa\u00edses:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-803 aligncenter\" src=\"https:\/\/asipi.org\/brasil2018\/wp-content\/uploads\/sites\/13\/2018\/05\/vaccines_02.jpg\" alt=\"\" width=\"486\" height=\"204\" \/><\/p>\n<p style=\"text-align: justify;\">Por lo tanto, debe obtener su certificado en un centro oficial de vacunaci\u00f3n contra la fiebre amarilla designado por los respectivos departamentos de salud estatales de su ciudad y \/ o pa\u00eds que administran vacunas contra la fiebre amarilla fabricadas con la aprobaci\u00f3n de la Organizaci\u00f3n Mundial de la Salud.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, recomendamos esta vacunaci\u00f3n para todos los brasile\u00f1os, extranjeros o turistas que tengan la intenci\u00f3n de visitar estos estados brasile\u00f1os:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-802 aligncenter\" src=\"https:\/\/asipi.org\/brasil2018\/wp-content\/uploads\/sites\/13\/2018\/05\/vaccines_03.jpg\" alt=\"\" width=\"351\" height=\"243\" \/><\/p>\n<p style=\"text-align: justify;\">PD La vacunaci\u00f3n debe tomarse (10) diez d\u00edas antes de viajar, al menos.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-chat-inv\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbIdioma\u00bb tab_id=\u00bb1525445912414-320ecd2b-699b\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">El idioma oficial es el portugu\u00e9s. Se habla algo de ingl\u00e9s, particularmente en las principales ciudades, pero lo m\u00e1s parecido a un segundo idioma es el espa\u00f1ol, con el que generalmente podr\u00e1 hacerse entender.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-target\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbDinero\u00bb tab_id=\u00bb1525445912457-3a3bb675-e97b\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">La moneda brasile\u00f1a es REAL. Todos los bancos y casas de cambio aceptan cheques de viajero y moneda extranjera. Es aconsejable tomar cheques de viajero en d\u00f3lares estadounidenses o divisas ya que esto se intercambia m\u00e1s f\u00e1cilmente que otras monedas.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-clock\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbHora\u00bb tab_id=\u00bb1525446071836-2b8b1359-75e2&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Brasil abarca varias zonas horarias, sin embargo, el horario est\u00e1ndar brasile\u00f1o es 3 horas antes que G.M.T. y 2 horas antes en el verano (de octubre a febrero).<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-tag\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbSeguridad General\u00bb tab_id=\u00bb1525446191629-63b1a129-897e\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Brasil, especialmente Rio, ha tenido una mala reputaci\u00f3n de seguridad personal y muchos visitantes potenciales se han pospuesto para viajar all\u00ed. Gran parte de esta reputaci\u00f3n puede atribuirse a exageraciones descabelladas, pero ha tenido el efecto beneficioso de estimular a las diversas autoridades de la ciudad para que hagan algo al respecto. Ahora hay mucha m\u00e1s polic\u00eda de turistas, que son mucho m\u00e1s \u00fatiles para los visitantes, y hay un patrullaje mucho mejor de las \u00e1reas problem\u00e1ticas. Aunque se est\u00e1 haciendo mucho m\u00e1s para mejorar la seguridad, el conocimiento de lo siguiente disminuir\u00e1 el riesgo para usted y sus pertenencias.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-flash\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbElectricidad\u00bb tab_id=\u00bb1525446260708-0f496057-15ab\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">La corriente el\u00e9ctrica en la mayor parte de Brasil es de 110v. Muchos hoteles tienen adaptadores si es necesario, aunque se recomienda traer sus propios adaptadores de viaje.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-umbrella\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbClima\u00bb tab_id=\u00bb1525446331655-46191f30-6a10&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">El clima var\u00eda desde un matorral \u00e1rido hacia el interior hasta una selva tropical intransitable de la selva amaz\u00f3nica septentrional y las playas costeras del este tropical. El sur es m\u00e1s templado. Las estaciones lluviosas ocurren de enero a abril en el norte (el promedio de d\u00edas cuando hay algo de lluvia es de 22); De abril a julio en el noreste (el n\u00famero promedio de d\u00edas cuando llueve es 14); Diciembre a marzo en el \u00e1rea de R\u00edo \/ Sao Paulo (el n\u00famero promedio de d\u00edas cuando llueve es 10).<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-compass\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbImpuestos\u00bb tab_id=\u00bb1525454170038-6caabf5f-ff60&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Los impuestos aeroportuarios generalmente est\u00e1n incluidos en el precio del boleto. Para promover el turismo y las convenciones, la mayor\u00eda de los hoteles cobran una tarifa no obligatoria que oscila entre U $ 1,00 y U $ 7,00 por habitaci\u00f3n y noche, dependiendo de la categor\u00eda del hotel como contribuci\u00f3n al Convention Bureau. Si los hu\u00e9spedes desean denegar el pago, deben informarlo al recepcionista a la salida.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_tour][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_btn title=\u00bbDescargar Informaci\u00f3n en Espa\u00f1ol\u00bb style=\u00bbclassic\u00bb color=\u00bbgreen\u00bb align=\u00bbcenter\u00bb i_icon_fontawesome=\u00bbfa fa-file-pdf-o\u00bb button_block=\u00bbtrue\u00bb add_icon=\u00bbtrue\u00bb link=\u00bburl:http%3A%2F%2Fasipi.org%2Fbrasil2018%2Fwp-content%2Fuploads%2Fsites%2F13%2F2018%2F11%2Finf-uteis-esp.pdf|title:Informaci%C3%B3n%20de%20Inter%C3%A9s|target:%20_blank|\u00bb el_class=\u00bbcustom-button-long-arrow-right\u00bb][vc_btn title=\u00bbDescargar Informaci\u00f3n en Portugu\u00e9s\u00bb style=\u00bbclassic\u00bb color=\u00bbgreen\u00bb align=\u00bbcenter\u00bb i_icon_fontawesome=\u00bbfa fa-file-pdf-o\u00bb button_block=\u00bbtrue\u00bb add_icon=\u00bbtrue\u00bb el_class=\u00bbcustom-button-long-arrow-right\u00bb link=\u00bburl:http%3A%2F%2Fasipi.org%2Fbrasil2018%2Fwp-content%2Fuploads%2Fsites%2F13%2F2018%2F11%2Finf-uteis-port.pdf|title:Descargar%20Informaci%C3%B3n%20de%20Inter%C3%A9s|target:%20_blank|\u00bb]<div class=\"porto-image-frame \"><span class=\"img-thumbnail\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"\/\/asipi.org\/brasil2018\/wp-content\/uploads\/sites\/13\/2018\/05\/about_brasil_collage_02.jpg\" class=\"img-responsive img-box-shadow\" width=\"810\" height=\"810\"><\/span><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/4&#8243;]<div class=\"porto-image-frame \"><span class=\"img-thumbnail\"><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"\/\/asipi.org\/brasil2018\/wp-content\/uploads\/sites\/13\/2018\/05\/about_brasil_collage_01.jpg\" class=\"img-responsive img-box-shadow\" width=\"810\" height=\"810\"><\/span><\/div>[\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_tta_tour color=\u00bbgreen\u00bb active_section=\u00bb1&#8243; no_fill_content_area=\u00bbtrue\u00bb][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-star\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbComida Brasile\u00f1a\u00bb tab_id=\u00bb1525387694678-84741c4b-ba3c\u00bb][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Los platos m\u00e1s comunes incluyen carnes variadas, arroz y frijoles negros brasile\u00f1os (feij\u00e3o), mientras que los restaurantes a menudo ofrecen barbacoas y bufetes de todo lo que pueda comer. Brasil tambi\u00e9n tiene muchas variedades regionales de cocina. Un ejemplo es la cocina de Bah\u00eda, que incluye platos tales como: Vatapa (camarones, aceite de pescado, leche de coco, pan y arroz), Sarapatel (h\u00edgado, coraz\u00f3n, tomates, pimientos, cebollas y salsa). Desde Rio Grande do Sul, un plato t\u00edpico es el Churrasco (una especie de barbacoa). Del Amazonas viene Tacaca (sopa espesa con gambas y ajo).<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-user\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbRopa\u00bb tab_id=\u00bb1525387694714-d70590e3-ad55&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">El clima de Brasil var\u00eda de tropical en el norte a templado en el sur. En todo el pa\u00eds, sin embargo, la vestimenta es informal. Por lo general, las camisas de algod\u00f3n liviano, los pantalones cortos, los vestidos y los pantalones son ideales para llevar durante el d\u00eda, mientras que por la noche las camisas de manga larga y los zapatos de cuero son normales. Normalmente no necesitar\u00e1 una chaqueta y corbata en Brasil. En su invierno (junio \/ septiembre) vale la pena traer algo caliente, ya que la temperatura puede ser bastante fr\u00eda en el sur del pa\u00eds.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-aperture-alt\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbCompras\u00bb tab_id=\u00bb1525388035285-07225412-80c1&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">Al igual que con la comida, en un pa\u00eds del tama\u00f1o de Brasil hay muchas especialidades locales para el comprador. En la mayor\u00eda de las principales ciudades, los centros comerciales permanecen abiertos hasta tarde (hasta las 10.00 p. M.), Mientras que las tiendas de la calle cierran a las 6 p.m. Artes y artesan\u00edas de buena calidad est\u00e1n disponibles en los mercados al aire libre regulares, que son lugares coloridos y entretenidos para los turistas a visitar.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-sun-inv\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbBeaches\u00bb tab_id=\u00bb1525388131690-81d7c223-c8e7&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">A significant part of Brazilian culture and the Brazilian of leisure centers around the beach. Thus, the beaches can be very fun and relaxing places. Do not forget the sun in Brazil can focus more directly and more strongly than in Europe, and take precautions. Certain areas, especially in Rio de Janeiro, have dangerous currents. Knowing this, stay close to other bathers and obey the warning flags: Red &#8211; Danger. It is strongly discouraged to enter the sea. White: The water is safe.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-award-empty\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbPropinas\u00bb tab_id=\u00bb1525389172249-36cbce9d-1719&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify;\">En la mayor\u00eda de los restaurantes y bares se agrega una tarifa de servicio del 10% a la factura. Los lugares m\u00e1s sofisticados pueden agregar un 15%. Si el servicio no est\u00e1 incluido, se indicar\u00e1 en la parte inferior de la factura: \u00abServi\u00e7o n\u00e3o inclu\u00eddo\u00bb. Los taxistas no esperan una propina, pero es normal redondear el precio final. Debe tener en cuenta que la cantidad que se muestra en el tax\u00edmetro puede no corresponderse siempre con la cantidad que debe pagar: busque una hoja separada pegada a la ventana que le indicar\u00e1 cu\u00e1nto equivale la cantidad en el medidor.<\/p>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_tour][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_separator color=\u00bbgreen\u00bb align=\u00bbalign_left\u00bb border_width=\u00bb4&#8243; el_width=\u00bb70&#8243;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb2\/3&#8243;][vc_tta_tour color=\u00bbgreen\u00bb active_section=\u00bb1&#8243; no_fill_content_area=\u00bbtrue\u00bb][vc_tta_section i_type=\u00bbopeniconic\u00bb i_icon_openiconic=\u00bbvc-oi vc-oi-user\u00bb add_icon=\u00bbtrue\u00bb title=\u00bbSalud\u00bb tab_id=\u00bb1525446452216-012660fe-7ecd\u00bb][vc_column_text] No hay requisitos de salud obligatorios para ingresar a Brasil. Se recomiendan precauciones para la [&hellip;]<\/p>\n","protected":false},"author":2640,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-781","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/pages\/781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/users\/2640"}],"replies":[{"embeddable":true,"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/comments?post=781"}],"version-history":[{"count":44,"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/pages\/781\/revisions"}],"predecessor-version":[{"id":3244,"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/pages\/781\/revisions\/3244"}],"wp:attachment":[{"href":"https:\/\/asipi.org\/brasil2018\/wp-json\/wp\/v2\/media?parent=781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}