{"id":240,"date":"2016-12-27T14:08:54","date_gmt":"2016-12-27T14:08:54","guid":{"rendered":"http:\/\/puertorico2017.asipi.org\/?page_id=240"},"modified":"2016-12-28T01:17:09","modified_gmt":"2016-12-28T01:17:09","slug":"lugares-turisticos","status":"publish","type":"page","link":"https:\/\/asipi.org\/puertorico2017\/lugares-turisticos\/","title":{"rendered":"Lugares Tur\u00edsticos"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\"><strong>San Juan de Puerto Rico<\/strong><\/h2>\n<p style=\"text-align: justify;\">Es la metr\u00f3poli del Caribe, con grandes y modernos edificios, y ocupa el lugar 71 como ciudad de mayor calidad de vida en el mundo. El \u00e1rea cubre siete bloques cuadrados de calles estrechas pavimentadas con adoquines, alineadas con antiguas casas coloniales con sus balcones y patios. Las fortalezas y las paredes del Viejo San Juan est\u00e1n entre las mejor preservadas del hemisferio. El \u00e1rea est\u00e1 repleta de casas, iglesias y plazas antiguas que representan la arquitectura m\u00e1s apreciada de\u00a0<a href=\"https:\/\/turismo.org\/el-caribe\/\">Caribe<\/a>.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_empty_space][vc_images_carousel images=\u00bb182,249,245&#8243; img_size=\u00bb350&#215;250&#8243; autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u00bb40px\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/3&#8243;][vc_empty_space][vc_images_carousel images=\u00bb177,255,178,173&#8243; img_size=\u00bb350&#215;250&#8243; autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\"><strong>La Fortaleza<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Se trata de una fortificaci\u00f3n del Siglo XVI, construida en el extremo norte de la isleta de San Juan. Por mucho tiempo, vigil\u00f3 la entrada a la bah\u00eda de San Juan y protegi\u00f3 la ciudad de ataques mar\u00edtimos. Adem\u00e1s, destaca La Fortaleza, (actual residencia oficial del Gobernador de Puerto Rico), conocida tambi\u00e9n como el palacio de Santa Catalina y el fuerte de San Crist\u00f3bal. Esta estructura, fue construida para proteger la ciudad de ataques terrestres, a diferencia del fuerte San Felipe del Morro, que proteg\u00eda la entrada mar\u00edtima.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u00bb40px\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\"><strong>Catedral Metropolitana de San Juan<\/strong><\/h2>\n<p style=\"text-align: justify;\">La Catedral Metropolitana de San Juan Bautista de Puerto Rico, es la sede de la archidi\u00f3cesis de San Juan. Contiene los restos del explorador y conquistador Juan Ponce de Le\u00f3n, as\u00ed como del m\u00e1rtir San P\u00edo. Guarda algunas reliquias, como las de los ornamentos y vestiduras usadas por el Papa Juan Pablo II en su visita a Puerto Rico en 1984.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb40px\u00bb][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_empty_space][vc_images_carousel images=\u00bb252,253&#8243; img_size=\u00bb350&#215;250&#8243; autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00bb2\/3&#8243;][vc_column_text] San Juan de Puerto Rico Es la metr\u00f3poli del Caribe, con grandes y modernos edificios, y ocupa el lugar 71 como ciudad de mayor calidad de vida en el mundo. El \u00e1rea cubre siete bloques cuadrados de calles estrechas pavimentadas con adoquines, alineadas con antiguas casas coloniales con sus balcones y patios. Las fortalezas y las paredes del Viejo San Juan est\u00e1n entre las mejor preservadas del hemisferio. El \u00e1rea est\u00e1 repleta de casas, iglesias y plazas antiguas que representan la arquitectura m\u00e1s apreciada de\u00a0Caribe. [\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/3&#8243;][vc_empty_space][vc_images_carousel images=\u00bb182,249,245&#8243; img_size=\u00bb350&#215;250&#8243; autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u00bb40px\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/3&#8243;][vc_empty_space][vc_images_carousel images=\u00bb177,255,178,173&#8243; img_size=\u00bb350&#215;250&#8243; autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text] La Fortaleza &nbsp; Se trata de una fortificaci\u00f3n del Siglo XVI, construida en el extremo norte de la<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-240","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/pages\/240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/comments?post=240"}],"version-history":[{"count":16,"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/pages\/240\/revisions"}],"predecessor-version":[{"id":316,"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/pages\/240\/revisions\/316"}],"wp:attachment":[{"href":"https:\/\/asipi.org\/puertorico2017\/wp-json\/wp\/v2\/media?parent=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}